{"id":78,"count":7,"description":"","link":"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/","name":"Bizden Haberler","slug":"bizden-haberler","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bizden Haberler ar\u015fivleri - Plazacubes EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bizden Haberler ar\u015fivleri - Plazacubes EN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/\" \/>\n<meta property=\"og:site_name\" content=\"Plazacubes EN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/blog\\\/category\\\/bizden-haberler\\\/\",\"url\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/blog\\\/category\\\/bizden-haberler\\\/\",\"name\":\"Bizden Haberler ar\u015fivleri - Plazacubes EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/blog\\\/category\\\/bizden-haberler\\\/#breadcrumb\"},\"inLanguage\":\"tr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/blog\\\/category\\\/bizden-haberler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bizden Haberler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/\",\"name\":\"Plazacubes EN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/#organization\",\"name\":\"Plazacubes EN\",\"url\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/cropped-PC-20.Yil-Seffaf-Arka-Plan.png\",\"contentUrl\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/cropped-PC-20.Yil-Seffaf-Arka-Plan.png\",\"width\":1632,\"height\":311,\"caption\":\"Plazacubes EN\"},\"image\":{\"@id\":\"https:\\\/\\\/plazacubes.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bizden Haberler ar\u015fivleri - Plazacubes EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/","og_locale":"tr_TR","og_type":"article","og_title":"Bizden Haberler ar\u015fivleri - Plazacubes EN","og_url":"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/","og_site_name":"Plazacubes EN","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/","url":"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/","name":"Bizden Haberler ar\u015fivleri - Plazacubes EN","isPartOf":{"@id":"https:\/\/plazacubes.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/#breadcrumb"},"inLanguage":"tr"},{"@type":"BreadcrumbList","@id":"https:\/\/plazacubes.com\/en\/blog\/category\/bizden-haberler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/plazacubes.com\/en\/"},{"@type":"ListItem","position":2,"name":"Bizden Haberler"}]},{"@type":"WebSite","@id":"https:\/\/plazacubes.com\/en\/#website","url":"https:\/\/plazacubes.com\/en\/","name":"Plazacubes EN","description":"","publisher":{"@id":"https:\/\/plazacubes.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plazacubes.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/plazacubes.com\/en\/#organization","name":"Plazacubes EN","url":"https:\/\/plazacubes.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/plazacubes.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/plazacubes.com\/en\/wp-content\/uploads\/sites\/2\/2026\/02\/cropped-PC-20.Yil-Seffaf-Arka-Plan.png","contentUrl":"https:\/\/plazacubes.com\/en\/wp-content\/uploads\/sites\/2\/2026\/02\/cropped-PC-20.Yil-Seffaf-Arka-Plan.png","width":1632,"height":311,"caption":"Plazacubes EN"},"image":{"@id":"https:\/\/plazacubes.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/plazacubes.com\/en\/wp-json\/wp\/v2\/categories\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazacubes.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/plazacubes.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/plazacubes.com\/en\/wp-json\/wp\/v2\/posts?categories=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}